{"id":8224,"date":"2025-07-07T09:30:00","date_gmt":"2025-07-07T07:30:00","guid":{"rendered":"https:\/\/famicord.lu\/?post_type=pregnancy_zone&#038;p=8224"},"modified":"2025-12-19T12:50:45","modified_gmt":"2025-12-19T11:50:45","slug":"sac-gestationnel","status":"publish","type":"pregnancy_zone","link":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel","title":{"rendered":"Sac gestationnel \u2013 quelle est sa fonction ?"},"content":{"rendered":"\n<p class=\" eplus-wrapper\">Le premier signe d&#8217;une grossesse bien localis\u00e9e est la visualisation du sac gestationnel dans l&#8217;ut\u00e9rus lors d&#8217;une \u00e9chographie. Cependant, la seule pr\u00e9sence du sac gestationnel ne signifie pas n\u00e9cessairement qu\u2019il s\u2019agit d\u2019une grossesse en d\u00e9veloppement normal. Que signifie donc la pr\u00e9sence d\u2019un sac gestationnel vide ?<\/p>\n\n\n\n<h2 class=\" wp-block-heading eplus-wrapper\"><strong>Qu&#8217;est-ce que le sac gestationnel ?<\/strong><\/h2>\n\n\n\n<p class=\" eplus-wrapper\">Le sac gestationnel (SG) est une petite structure ronde remplie de liquide et repr\u00e9sente le premier stade d&#8217;une grossesse pr\u00e9coce. Avant de pouvoir d\u00e9tecter l\u2019embryon et son activit\u00e9 cardiaque, il permet de v\u00e9rifier si la grossesse est bien implant\u00e9e dans l\u2019ut\u00e9rus. Apr\u00e8s l\u2019apparition du sac gestationnel, se d\u00e9veloppent ensuite dans l\u2019ordre suivant : le sac vitellin, l\u2019embryon et la cavit\u00e9 amniotique.<\/p>\n\n\n\n<h2 class=\" wp-block-heading eplus-wrapper\"><strong>Sac gestationnel \u2013 \u00e9chographie<\/strong><\/h2>\n\n\n\n<p class=\" eplus-wrapper\">La plupart des femmes passent leur premi\u00e8re \u00e9chographie apr\u00e8s un test de grossesse positif dans l&#8217;urine ou le sang \u2013 g\u00e9n\u00e9ralement entre la 5e et la 7e semaine de grossesse. Le sac gestationnel devrait \u00eatre visible lorsque le taux de b\u00eata-hCG atteint environ 1500 UI\/ml. Le gyn\u00e9cologue v\u00e9rifie alors la position du sac dans l\u2019ut\u00e9rus, le mesure et d\u00e9termine combien de sacs sont pr\u00e9sents. Si le taux de b\u00eata-hCG est \u00e9lev\u00e9 mais qu\u2019aucun sac gestationnel n\u2019est visible dans l\u2019ut\u00e9rus, il existe un risque \u00e9lev\u00e9 de grossesse extra-ut\u00e9rine.<\/p>\n\n\n\n<h2 class=\" wp-block-heading eplus-wrapper\"><strong>Taille du sac gestationnel<\/strong><\/h2>\n\n\n\n<p class=\" eplus-wrapper\">La taille du sac gestationnel \u00e0 l\u2019\u00e9chographie permet d\u2019estimer l\u2019\u00e2ge gestationnel \u2013 m\u00eame avant que la longueur cranio-caudale (CRL) de l\u2019embryon puisse \u00eatre mesur\u00e9e. Valeurs indicatives :<\/p>\n\n\n<ul class=\" wp-block-list eplus-wrapper eplus-styles-uid-8d6d9f\">\n<li class=\" eplus-wrapper\">Sac gestationnel de 1 \u00e0 4 mm = 4e\/5e semaine de grossesse<\/li>\n\n\n\n<li class=\" eplus-wrapper\">Sac gestationnel de 5 \u00e0 8 mm = 5e\/6e semaine de grossesse<\/li>\n<\/ul>\n\n\n<p class=\" eplus-wrapper\">La croissance normale du sac est d\u2019environ 1 \u00e0 1,2 mm par jour. Si le sac mesure plus de 20 mm sans qu\u2019un embryon soit visible, le risque de fausse couche est tr\u00e8s \u00e9lev\u00e9 (appel\u00e9e \u00ab \u0153uf clair \u00bb ou grossesse sans embryon).<\/p>\n\n\n\n<h2 class=\" wp-block-heading eplus-wrapper\"><strong>Sac gestationnel vide<\/strong><\/h2>\n\n\n\n<p class=\" eplus-wrapper\">Un sac gestationnel vide \u00e0 l\u2019\u00e9chographie signifie qu\u2019il s\u2019agit d\u2019une grossesse sans embryon. Le sac vitellin et la cavit\u00e9 amniotique peuvent se d\u00e9velopper normalement, mais l\u2019embryon ne se forme pas ou est r\u00e9absorb\u00e9 \u00e0 un stade tr\u00e8s pr\u00e9coce. Un sac vide est \u00e9quivalent \u00e0 une fausse couche. Les causes les plus fr\u00e9quentes sont des anomalies g\u00e9n\u00e9tiques. Mais cela peut aussi \u00eatre d\u00fb \u00e0 des troubles immunologiques ou \u00e0 des infections. Important : un sac gestationnel vide n\u2019augmente pas le risque de fausse couche lors de grossesses futures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le premier signe d&#8217;une grossesse bien localis\u00e9e est la visualisation du sac gestationnel dans l&#8217;ut\u00e9rus lors d&#8217;une \u00e9chographie. Cependant, la seule pr\u00e9sence du sac gestationnel ne signifie pas n\u00e9cessairement qu\u2019il s\u2019agit d\u2019une grossesse en d\u00e9veloppement normal. Que signifie donc la pr\u00e9sence d\u2019un sac gestationnel vide ? Qu&#8217;est-ce que le sac gestationnel ? Le sac gestationnel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8222,"template":"","pregnancy_zone_category":[91],"class_list":["post-8224","pregnancy_zone","type-pregnancy_zone","status-publish","has-post-thumbnail","hentry","pregnancy_zone_category-informations-sur-la-grossesse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sac gestationnel pendant la grossesse | FamiCord Suisse<\/title>\n<meta name=\"description\" content=\"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sac gestationnel pendant la grossesse | FamiCord Suisse\" \/>\n<meta property=\"og:description\" content=\"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel\" \/>\n<meta property=\"og:site_name\" content=\"Famicord Suisse\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T11:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/famicord.lu\/wp-content\/uploads\/2025\/07\/Fruchthoehle.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel\",\"url\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel\",\"name\":\"Sac gestationnel pendant la grossesse | FamiCord Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/famicord.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fruchthoehle.webp\",\"datePublished\":\"2025-07-07T07:30:00+00:00\",\"dateModified\":\"2025-12-19T11:50:45+00:00\",\"description\":\"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel#breadcrumb\"},\"inLanguage\":\"fr-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel#primaryimage\",\"url\":\"https:\\\/\\\/famicord.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fruchthoehle.webp\",\"contentUrl\":\"https:\\\/\\\/famicord.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fruchthoehle.webp\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\\\/informations-sur-la-grossesse\\\/sac-gestationnel#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/famicord.lu\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FamiBlog\",\"item\":\"https:\\\/\\\/famicord.lu\\\/fr\\\/pregnancy-zone-2\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sac gestationnel \u2013 quelle est sa fonction ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/famicord.lu\\\/fr#website\",\"url\":\"https:\\\/\\\/famicord.lu\\\/fr\",\"name\":\"FamiCord Suisse\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/famicord.lu\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-LU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sac gestationnel pendant la grossesse | FamiCord Suisse","description":"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel","og_locale":"fr_FR","og_type":"article","og_title":"Sac gestationnel pendant la grossesse | FamiCord Suisse","og_description":"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.","og_url":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel","og_site_name":"Famicord Suisse","article_modified_time":"2025-12-19T11:50:45+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/famicord.lu\/wp-content\/uploads\/2025\/07\/Fruchthoehle.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel","url":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel","name":"Sac gestationnel pendant la grossesse | FamiCord Suisse","isPartOf":{"@id":"https:\/\/famicord.lu\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel#primaryimage"},"image":{"@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel#primaryimage"},"thumbnailUrl":"https:\/\/famicord.lu\/wp-content\/uploads\/2025\/07\/Fruchthoehle.webp","datePublished":"2025-07-07T07:30:00+00:00","dateModified":"2025-12-19T11:50:45+00:00","description":"Qu\u2019est-ce que le sac gestationnel et quelle est sa fonction ? D\u00e9couvrez ce que signifie un sac gestationnel vide et quand consulter un m\u00e9decin.","breadcrumb":{"@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel#breadcrumb"},"inLanguage":"fr-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel"]}]},{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel#primaryimage","url":"https:\/\/famicord.lu\/wp-content\/uploads\/2025\/07\/Fruchthoehle.webp","contentUrl":"https:\/\/famicord.lu\/wp-content\/uploads\/2025\/07\/Fruchthoehle.webp","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2\/informations-sur-la-grossesse\/sac-gestationnel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/famicord.lu\/fr"},{"@type":"ListItem","position":2,"name":"FamiBlog","item":"https:\/\/famicord.lu\/fr\/pregnancy-zone-2"},{"@type":"ListItem","position":3,"name":"Sac gestationnel \u2013 quelle est sa fonction ?"}]},{"@type":"WebSite","@id":"https:\/\/famicord.lu\/fr#website","url":"https:\/\/famicord.lu\/fr","name":"FamiCord Suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/famicord.lu\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-LU"}]}},"_links":{"self":[{"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/pregnancy_zone\/8224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/pregnancy_zone"}],"about":[{"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/types\/pregnancy_zone"}],"author":[{"embeddable":true,"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/users\/4"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/media\/8222"}],"wp:attachment":[{"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/media?parent=8224"}],"wp:term":[{"taxonomy":"pregnancy_zone_category","embeddable":true,"href":"https:\/\/famicord.lu\/fr\/wp-json\/wp\/v2\/pregnancy_zone_category?post=8224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}